{"id":12869,"date":"2025-05-15T08:31:14","date_gmt":"2025-05-15T11:31:14","guid":{"rendered":"http:\/\/www.trocandofraldas.com.br\/?p=12869"},"modified":"2025-07-16T07:50:08","modified_gmt":"2025-07-16T10:50:08","slug":"espina-bifida","status":"publish","type":"post","link":"https:\/\/www.famivita.com.br\/conteudo\/es\/espina-bifida\/","title":{"rendered":"Espina b\u00edfida \u2013 \u00bfQu\u00e9 es?"},"content":{"rendered":"<p class=\"align-justify\">Entre las diversas anomal\u00edas que pueden ocurrir durante el desarrollo fetal, una poco conocida es la espina b\u00edfida o columna bifurcada, como tambi\u00e9n la llaman los m\u00e9dicos. La espina b\u00edfida es una malformaci\u00f3n cong\u00e9nita considerada com\u00fan por presentarse en muchos casos y se caracteriza por una formaci\u00f3n inadecuada y el cierre incorrecto del tubo neural del embri\u00f3n.<a href=\"https:\/\/www.famivita.com.br\/conteudo\/wp-content\/uploads\/Espinha-Bifida-\u2013-O-que-e-Isso-1.jpg\"><\/p>\n<p class=\"align-justify\">El problema se produce en los dos primeros meses de gestaci\u00f3n, cuando algunas <strong>v\u00e9rtebras que recubren la m\u00e9dula<\/strong> no llegan a formarse completamente, dejando un espacio abierto en la zona. Con este espacio abierto, la m\u00e9dula espinal termina sobresaliendo y proyect\u00e1ndose fuera de los huesos, siendo f\u00e1cilmente visible externamente. Existen 3 tipos de anomal\u00edas relacionadas con las malformaciones de la espina b\u00edfida: la meningocele, la mielomeningocele y la espina b\u00edfida oculta.<\/p>\n<ul>\n<li class=\"align-justify\"><strong>Meningocele<\/strong> &#8211; Considerada la forma m\u00e1s leve de la espina b\u00edfida, la meningocele ocasiona una peque\u00f1a protuberancia en la espalda del beb\u00e9 que afecta solamente a las estructuras de protecci\u00f3n de la m\u00e9dula espinal, pero manteni\u00e9ndola dentro de las v\u00e9rtebras como es lo normal.<\/li>\n<\/ul>\n<ul>\n<li><strong>Mielomeningocele \u2013<\/strong> Considerado el caso m\u00e1s grave de espina b\u00edfida, adem\u00e1s de la gran protuberancia visible, las estructuras de protecci\u00f3n de la m\u00e9dula est\u00e1n completamente abiertas, provocando que el beb\u00e9 tenga problemas neurol\u00f3gicos que impiden la transmisi\u00f3n de los impulsos nerviosos.<\/li>\n<\/ul>\n<ul>\n<li><strong>Espina B\u00edfida Oculta \u2013<\/strong> El tipo m\u00e1s com\u00fan y caracterizado por el cierre incompleto de la columna, pero que no afecta ni compromete a la m\u00e9dula ni a sus estructuras. Al ser uno de los casos que no afectan al sistema neurol\u00f3gico, puede incluso pasar desapercibido. Una de las se\u00f1ales habituales de este tipo es la presencia de vello o una mancha en la zona afectada.<\/li>\n<\/ul>\n<p class=\"align-justify\">Entre las principales causas de esta patolog\u00eda se encuentran la edad avanzada de los progenitores, madres diab\u00e9ticas, <a href=\"https:\/\/www.famivita.com.br\/conteudo\/es\/acido-folico-embarazo-previene-malformaciones\/\">falta de \u00e1cido f\u00f3lico<\/a> en el organismo de la madre, consumo de alcohol durante el embarazo y alteraciones gen\u00e9ticas. La espina b\u00edfida puede diagnosticarse a trav\u00e9s de una <a href=\"https:\/\/www.famivita.com.br\/conteudo\/es\/categoria\/ultrasonido-embarazo\/\">ecograf\u00eda<\/a> en el primer trimestre de gestaci\u00f3n.<\/p>\n<h2>Tratamiento para la Espina B\u00edfida<\/h2>\n<p class=\"align-justify\">El tratamiento adecuado para la espina b\u00edfida depender\u00e1 de su tipo y en muchos casos <strong>no es necesario ning\u00fan tipo de tratamiento<\/strong>. Como ya mencionamos antes, en el caso de la espina b\u00edfida oculta el problema puede pasar desapercibido, ya que no presenta s\u00edntomas ni dificultades para el ni\u00f1o. Normalmente, el tratamiento recomendado es mediante cirug\u00eda de reparaci\u00f3n, la cual debe realizarse en los primeros d\u00edas de vida del beb\u00e9. El objetivo es introducir toda la estructura dentro de la columna en su sitio adecuado cerrando as\u00ed la deformidad. Sin embargo, es importante advertir que esta cirug\u00eda casi nunca logra evitar los problemas neurol\u00f3gicos causados por la espina b\u00edfida.<a href=\"https:\/\/www.famivita.com.br\/conteudo\/wp-content\/uploads\/Espinha-Bifida-\u2013-O-que-e-Isso-2.jpg\"><\/p>\n<p class=\"align-justify\">En los casos de mielomeningocele, el beb\u00e9 tambi\u00e9n debe someterse a la <strong>reparaci\u00f3n quir\u00fargica en<\/strong> los primeros d\u00edas de vida. Hasta que se realice la cirug\u00eda, el beb\u00e9 debe permanecer en posici\u00f3n boca abajo, permitiendo que la peque\u00f1a apertura quede hacia arriba y cubierta con gasas empapadas en suero fisiol\u00f3gico, evitando as\u00ed riesgos de infecciones locales. Cuando la hidrocefalia ocurre al mismo tiempo que la espina b\u00edfida, la extracci\u00f3n del exceso de l\u00edquido del cerebro tambi\u00e9n debe hacerse mediante cirug\u00eda, con el fin de reducir y prevenir mayores consecuencias en la salud del ni\u00f1o. Adem\u00e1s de la reparaci\u00f3n quir\u00fargica, <strong>la fisioterapia es de gran importancia en el tratamiento<\/strong> y se centra en fortalecer la columna y los m\u00fasculos intestinales y de la vejiga, proporcionando mayor autonom\u00eda al ni\u00f1o, en algunos casos ayudando y fortaleciendo la capacidad de caminar o incluso de usar silla de ruedas. Las sesiones de fisioterapia tambi\u00e9n sirven para disminuir y prevenir el desarrollo de deformidades en la zona, as\u00ed como para aumentar el control sobre el cuerpo.<\/p>\n<p class=\"align-justify\">Vea tambi\u00e9n:\u00a0<a title=\"\u00c1cido F\u00f3lico en el Embarazo Previene Malformaciones\" href=\"https:\/\/www.famivita.com.br\/conteudo\/es\/acido-folico-embarazo-previene-malformaciones\/\" rel=\"bookmark\">\u00c1cido F\u00f3lico en el Embarazo Previene Malformaciones <\/a><\/p>\n<p class=\"align-justify\">Fotos: Laurinda, rafaelgenu<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una de las diversas anomal\u00edas que pueden ocurrir durante el desarrollo fetal es la espina b\u00edfida. \u00a1Este hecho ocurre ya en los primeros meses del embarazo!<\/p>\n","protected":false},"author":471399,"featured_media":12873,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1007],"tags":[94,39,54],"class_list":["post-12869","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultrasonido-embarazo","tag-desarrollo-fetal","tag-embarazo","tag-tratamientos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Espina b\u00edfida \u2013 \u00bfQu\u00e9 es? | Famivita<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/espina-bifida\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Espina b\u00edfida \u2013 \u00bfQu\u00e9 es? | Famivita\" \/>\n<meta property=\"og:description\" content=\"Una de las diversas anomal\u00edas que pueden ocurrir durante el desarrollo fetal es la espina b\u00edfida. \u00a1Este hecho ocurre ya en los primeros meses del embarazo!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/espina-bifida\/\" \/>\n<meta property=\"og:site_name\" content=\"Famivita\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-15T11:31:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-16T10:50:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/wp-content\/uploads\/Espinha-Bifida-\u2013-O-que-e-Isso-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"428\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dra. Mayara Belli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/espina-bifida\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/espina-bifida\/\"},\"author\":{\"name\":\"Dra. Mayara Belli\",\"@id\":\"https:\/\/www.famivita.com.br\/conteudo\/es\/#\/schema\/person\/1936f7c86b772cc44c19b926eee9cd53\"},\"headline\":\"Espina b\u00edfida \u2013 \u00bfQu\u00e9 es?\",\"datePublished\":\"2025-05-15T11:31:14+00:00\",\"dateModified\":\"2025-07-16T10:50:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/espina-bifida\/\"},\"wordCount\":713,\"commentCount\":4,\"image\":{\"@id\":\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/espina-bifida\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-content\/uploads\/Espinha-Bifida-\u2013-O-que-e-Isso-2.jpg\",\"keywords\":[\"desarrollo fetal\",\"embarazo\",\"tratamientos\"],\"articleSection\":[\"Ultrasonido en el Embarazo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/espina-bifida\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/espina-bifida\/\",\"url\":\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/espina-bifida\/\",\"name\":\"Espina b\u00edfida \u2013 \u00bfQu\u00e9 es? | Famivita\",\"isPartOf\":{\"@id\":\"https:\/\/www.famivita.com.br\/conteudo\/es\/#website\",\"sameAs\":[\"https:\/\/www.instagram.com\/famivita\/\",\"https:\/\/www.facebook.com\/famivita\/\",\"https:\/\/www.youtube.com\/user\/trocandofraldasyt\",\"https:\/\/api.whatsapp.com\/send\/?phone=5511917837433\"]},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/espina-bifida\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/espina-bifida\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-content\/uploads\/Espinha-Bifida-\u2013-O-que-e-Isso-2.jpg\",\"datePublished\":\"2025-05-15T11:31:14+00:00\",\"dateModified\":\"2025-07-16T10:50:08+00:00\",\"author\":{\"@id\":\"https:\/\/www.famivita.com.br\/conteudo\/es\/#\/schema\/person\/1936f7c86b772cc44c19b926eee9cd53\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/espina-bifida\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/espina-bifida\/\"]}],\"about\":{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.famivita.com.br\/#organization\",\"name\":\"Famivita\",\"logo\":\"https:\/\/www.famivita.com.br\/wp-content\/themes\/storefront-child\/header_footer_html\/images\/logo_mobile2.svg\",\"url\":\"https:\/\/www.famivita.com.br\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Rua Benedito Fernandes, 545, Santo Amaro\",\"addressLocality\":\"S\u00e3o Paulo\",\"addressRegion\":\"S\u00e3o Paulo\",\"postalCode\":\"04746-110\",\"addressCountry\":{\"@type\":\"Country\",\"name\":\"BR\"}}}},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/espina-bifida\/#primaryimage\",\"url\":\"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-content\/uploads\/Espinha-Bifida-\u2013-O-que-e-Isso-2.jpg\",\"contentUrl\":\"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-content\/uploads\/Espinha-Bifida-\u2013-O-que-e-Isso-2.jpg\",\"width\":640,\"height\":428,\"caption\":\"beb\u00ea recem nascido\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/espina-bifida\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.famivita.com.br\/conteudo\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Embarazo\",\"item\":\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/categoria\/embarazo\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ex\u00e1menes durante el Embarazo\",\"item\":\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/categoria\/examenes-durante-embarazo\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Ultrasonido en el Embarazo\",\"item\":\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/categoria\/ultrasonido-embarazo\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Espina b\u00edfida \u2013 \u00bfQu\u00e9 es?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.famivita.com.br\/conteudo\/es\/#website\",\"url\":\"https:\/\/www.famivita.com.br\/conteudo\/es\/\",\"name\":\"Famivita\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.famivita.com.br\/conteudo\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.famivita.com.br\/conteudo\/es\/#\/schema\/person\/1936f7c86b772cc44c19b926eee9cd53\",\"name\":\"Dra. Mayara Belli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/8ed5f690ca67f8fdcb41678043ebff57ec60fda2206c36ce32b5a125f0c6915f?s=96&d=mm&r=g\",\"url\":\"https:\/\/www.famivita.com.br\/conteudo\/wp-content\/uploads\/2022\/08\/mayara-belli-top.jpg\",\"contentUrl\":\"https:\/\/www.famivita.com.br\/conteudo\/wp-content\/uploads\/2022\/08\/mayara-belli-top.jpg\",\"caption\":\"Dra. Mayara Belli\"},\"description\":\"Graduada en Nutrici\u00f3n por la Universidad Anhembi Morumbi. Tiene un posgrado en Nutrici\u00f3n Materno-Infantil y formaci\u00f3n en Nutrici\u00f3n y Fertilidad. Adem\u00e1s, est\u00e1 formada como Natural Chef (gastronom\u00eda funcional) y actualmente trabaja en el \u00e1rea cl\u00ednica atendiendo nutricionalmente a mujeres que desean quedar embarazadas, parejas, gestantes, lactantes, ni\u00f1os y salud de la mujer.\",\"sameAs\":[\"https:\/\/www.instagram.com\/nutri.futuramamae\/\"],\"url\":\"https:\/\/www.famivita.com.br\/conteudo\/es\/author\/dra-mayara-belli\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Espina b\u00edfida \u2013 \u00bfQu\u00e9 es? | Famivita","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/espina-bifida\/","og_locale":"es_ES","og_type":"article","og_title":"Espina b\u00edfida \u2013 \u00bfQu\u00e9 es? | Famivita","og_description":"Una de las diversas anomal\u00edas que pueden ocurrir durante el desarrollo fetal es la espina b\u00edfida. \u00a1Este hecho ocurre ya en los primeros meses del embarazo!","og_url":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/espina-bifida\/","og_site_name":"Famivita","article_published_time":"2025-05-15T11:31:14+00:00","article_modified_time":"2025-07-16T10:50:08+00:00","og_image":[{"width":640,"height":428,"url":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/wp-content\/uploads\/Espinha-Bifida-\u2013-O-que-e-Isso-2.jpg","type":"image\/jpeg"}],"author":"Dra. Mayara Belli","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/espina-bifida\/#article","isPartOf":{"@id":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/espina-bifida\/"},"author":{"name":"Dra. Mayara Belli","@id":"https:\/\/www.famivita.com.br\/conteudo\/es\/#\/schema\/person\/1936f7c86b772cc44c19b926eee9cd53"},"headline":"Espina b\u00edfida \u2013 \u00bfQu\u00e9 es?","datePublished":"2025-05-15T11:31:14+00:00","dateModified":"2025-07-16T10:50:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/espina-bifida\/"},"wordCount":713,"commentCount":4,"image":{"@id":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/espina-bifida\/#primaryimage"},"thumbnailUrl":"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-content\/uploads\/Espinha-Bifida-\u2013-O-que-e-Isso-2.jpg","keywords":["desarrollo fetal","embarazo","tratamientos"],"articleSection":["Ultrasonido en el Embarazo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.famivita.com.br\/conteudo\/es-dev\/espina-bifida\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/espina-bifida\/","url":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/espina-bifida\/","name":"Espina b\u00edfida \u2013 \u00bfQu\u00e9 es? | Famivita","isPartOf":{"@id":"https:\/\/www.famivita.com.br\/conteudo\/es\/#website","sameAs":["https:\/\/www.instagram.com\/famivita\/","https:\/\/www.facebook.com\/famivita\/","https:\/\/www.youtube.com\/user\/trocandofraldasyt","https:\/\/api.whatsapp.com\/send\/?phone=5511917837433"]},"primaryImageOfPage":{"@id":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/espina-bifida\/#primaryimage"},"image":{"@id":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/espina-bifida\/#primaryimage"},"thumbnailUrl":"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-content\/uploads\/Espinha-Bifida-\u2013-O-que-e-Isso-2.jpg","datePublished":"2025-05-15T11:31:14+00:00","dateModified":"2025-07-16T10:50:08+00:00","author":{"@id":"https:\/\/www.famivita.com.br\/conteudo\/es\/#\/schema\/person\/1936f7c86b772cc44c19b926eee9cd53"},"breadcrumb":{"@id":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/espina-bifida\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.famivita.com.br\/conteudo\/es-dev\/espina-bifida\/"]}],"about":{"@type":"Organization","@id":"https:\/\/www.famivita.com.br\/#organization","name":"Famivita","logo":"https:\/\/www.famivita.com.br\/wp-content\/themes\/storefront-child\/header_footer_html\/images\/logo_mobile2.svg","url":"https:\/\/www.famivita.com.br\/","address":{"@type":"PostalAddress","streetAddress":"Rua Benedito Fernandes, 545, Santo Amaro","addressLocality":"S\u00e3o Paulo","addressRegion":"S\u00e3o Paulo","postalCode":"04746-110","addressCountry":{"@type":"Country","name":"BR"}}}},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/espina-bifida\/#primaryimage","url":"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-content\/uploads\/Espinha-Bifida-\u2013-O-que-e-Isso-2.jpg","contentUrl":"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-content\/uploads\/Espinha-Bifida-\u2013-O-que-e-Isso-2.jpg","width":640,"height":428,"caption":"beb\u00ea recem nascido"},{"@type":"BreadcrumbList","@id":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/espina-bifida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.famivita.com.br\/conteudo\/es\/"},{"@type":"ListItem","position":2,"name":"Embarazo","item":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/categoria\/embarazo\/"},{"@type":"ListItem","position":3,"name":"Ex\u00e1menes durante el Embarazo","item":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/categoria\/examenes-durante-embarazo\/"},{"@type":"ListItem","position":4,"name":"Ultrasonido en el Embarazo","item":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/categoria\/ultrasonido-embarazo\/"},{"@type":"ListItem","position":5,"name":"Espina b\u00edfida \u2013 \u00bfQu\u00e9 es?"}]},{"@type":"WebSite","@id":"https:\/\/www.famivita.com.br\/conteudo\/es\/#website","url":"https:\/\/www.famivita.com.br\/conteudo\/es\/","name":"Famivita","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.famivita.com.br\/conteudo\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.famivita.com.br\/conteudo\/es\/#\/schema\/person\/1936f7c86b772cc44c19b926eee9cd53","name":"Dra. Mayara Belli","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8ed5f690ca67f8fdcb41678043ebff57ec60fda2206c36ce32b5a125f0c6915f?s=96&d=mm&r=g","url":"https:\/\/www.famivita.com.br\/conteudo\/wp-content\/uploads\/2022\/08\/mayara-belli-top.jpg","contentUrl":"https:\/\/www.famivita.com.br\/conteudo\/wp-content\/uploads\/2022\/08\/mayara-belli-top.jpg","caption":"Dra. Mayara Belli"},"description":"Graduada en Nutrici\u00f3n por la Universidad Anhembi Morumbi. Tiene un posgrado en Nutrici\u00f3n Materno-Infantil y formaci\u00f3n en Nutrici\u00f3n y Fertilidad. Adem\u00e1s, est\u00e1 formada como Natural Chef (gastronom\u00eda funcional) y actualmente trabaja en el \u00e1rea cl\u00ednica atendiendo nutricionalmente a mujeres que desean quedar embarazadas, parejas, gestantes, lactantes, ni\u00f1os y salud de la mujer.","sameAs":["https:\/\/www.instagram.com\/nutri.futuramamae\/"],"url":"https:\/\/www.famivita.com.br\/conteudo\/es\/author\/dra-mayara-belli\/"}]}},"_links":{"self":[{"href":"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-json\/wp\/v2\/posts\/12869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-json\/wp\/v2\/users\/471399"}],"replies":[{"embeddable":true,"href":"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-json\/wp\/v2\/comments?post=12869"}],"version-history":[{"count":2,"href":"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-json\/wp\/v2\/posts\/12869\/revisions"}],"predecessor-version":[{"id":160854,"href":"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-json\/wp\/v2\/posts\/12869\/revisions\/160854"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-json\/wp\/v2\/media\/12873"}],"wp:attachment":[{"href":"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-json\/wp\/v2\/media?parent=12869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-json\/wp\/v2\/categories?post=12869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-json\/wp\/v2\/tags?post=12869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}