{"id":23110,"date":"2025-05-15T08:28:24","date_gmt":"2025-05-15T11:28:24","guid":{"rendered":"https:\/\/www.famivita.com.br\/conteudo\/es\/?p=23110"},"modified":"2025-07-16T07:52:31","modified_gmt":"2025-07-16T10:52:31","slug":"desgaste-mujer-despues-parto","status":"publish","type":"post","link":"https:\/\/www.famivita.com.br\/conteudo\/es\/desgaste-mujer-despues-parto\/","title":{"rendered":"Desgaste de la Mujer Despu\u00e9s del Parto"},"content":{"rendered":"<p class=\"align-justify\">\u00a1El gran d\u00eda ha llegado! Por fin conociste a ese peque\u00f1o ser que cambi\u00f3 tu vida, le dio m\u00e1s color a tu historia y trajo m\u00e1s expectativas a tu vida. Cuando llegas a casa, cada rinc\u00f3n y sus detalles, cuidados minuciosamente, empiezan a cobrar vida, pero junto con todo ese encanto, tambi\u00e9n llega el desgaste de la mujer despu\u00e9s del parto. \u00bfSer\u00e1 depresi\u00f3n posparto? \u00bfSue\u00f1o atrasado? \u00bfTengo anemia? \u00bfQu\u00e9 me est\u00e1 pasando al final? Es un cansancio tan grande, un agotamiento descontrolado que llega a preocupar. \u00bfPero qu\u00e9 est\u00e1 ocurriendo?<\/p>\n<p class=\"align-justify\">La gente imagina que despu\u00e9s del nacimiento del beb\u00e9, todo volver\u00e1 a la normalidad como por arte de magia. El peso de la barriga ya no incomodar\u00e1 y hasta las posiciones m\u00e1s c\u00f3modas para dormir podr\u00e1n regresar. La vanidad es obligatoria, as\u00ed como el \u00e1nimo para todos los eventos, especialmente los familiares. \u00bfPero te has parado a pensar <strong>cu\u00e1ntas transformaciones emocionales<\/strong> y no solo f\u00edsicas atraviesa una mujer durante los 9 meses?<\/p>\n<p class=\"align-justify\">Estar embarazada va mucho m\u00e1s all\u00e1 de solo gestar o albergar a un beb\u00e9 dentro de s\u00ed. Demanda mucho desgaste f\u00edsico y emocional y mucho <strong>preparaci\u00f3n psicol\u00f3gica<\/strong> para soportar las transformaciones e incomodidades generadas por el embarazo y a\u00fan lidiar con la presi\u00f3n y el <a href=\"https:\/\/www.famivita.com.br\/conteudo\/es\/lidiar-miedo-parto\/\">miedo al d\u00eda del parto<\/a>.<\/p>\n<p class=\"align-justify\">Cuando nace el beb\u00e9, tu cuerpo estar\u00e1 en proceso de recuperaci\u00f3n y por ello la fatiga es inevitable, a\u00fan m\u00e1s porque en vez de dormir para recomponerte tendr\u00e1s que cuidar 24 horas al d\u00eda de un reci\u00e9n nacido que se despierta todo el tiempo y necesita de cuidados continuos, adem\u00e1s de la lactancia materna que es un trabajo muy demandante y la <a href=\"https:\/\/www.famivita.com.br\/conteudo\/es\/la-menstruacion-posparto-cuando-vuelve-a-la-normalidad-y-los-riesgos-del-embarazo\/\">menstruaci\u00f3n posparto<\/a> que parece que nunca terminar\u00e1.<\/p>\n<p class=\"align-justify\">Por eso es tan natural escuchar de mujeres que acaban de dar a luz, que se sienten \u201cbasura\u201d. El desgaste de la mujer despu\u00e9s del parto <strong>no siempre est\u00e1 relacionado con la falta de vitaminas o una depresi\u00f3n posparto<\/strong>. En la mayor\u00eda de los casos, el desgaste est\u00e1 vinculado al cansancio natural de todo el proceso que vivi\u00f3 y est\u00e1 viviendo. Poder recomponerse y volver a su disposici\u00f3n normal puede tardar algunos meses, dependiendo de su rutina, de cu\u00e1nto logra descansar, del apoyo que recibe de su pareja y familia, e incluso de la cantidad de compromisos que tiene.<\/p>\n<p class=\"align-justify\">Adaptarse a la nueva vida y a la nueva rutina puede tomar algunos meses, aunque para algunas mujeres el proceso puede ser m\u00e1s r\u00e1pido. Lo importante es no ser demasiado exigente consigo misma ni querer hacer aquello que no se puede. <strong>Pedir ayuda<\/strong> tampoco es vergonzoso y decir que no puedes, \u00a1mucho menos! S\u00ed, las mujeres despu\u00e9s del parto necesitan ayuda y lo que puede ser m\u00ednimo para algunos, es de gran ayuda para ellas, a\u00fan m\u00e1s si tienen otros hijos.<\/p>\n<h2>\u00bfC\u00f3mo Aliviar el Desgaste Despu\u00e9s del Parto?<\/h2>\n<p class=\"align-justify\">Como tu cuerpo necesita adaptaci\u00f3n despu\u00e9s del nacimiento del beb\u00e9, aquella recomendaci\u00f3n tan repetida durante el embarazo ser\u00e1 a\u00fan m\u00e1s recordada ahora: \u201cDuerme todo lo que puedas\u201d. La falta de sue\u00f1o despu\u00e9s del nacimiento del beb\u00e9 realmente es uno de los puntos clave del desgaste tras el parto, ya que no existe mejor manera de reponerse que durmiendo para recargar energ\u00edas. Veamos <strong>algunos consejos<\/strong>:<\/p>\n<ul>\n<li>Los reci\u00e9n nacidos duermen muchas horas seguidas y se despiertan solo para mamar, cambiar pa\u00f1ales y ba\u00f1arse. <strong>Aprovecha estas largas siestas<\/strong> para descansar tambi\u00e9n, incluyendo por la noche, cuando lo acuestes a dormir, duerme pronto t\u00fa tambi\u00e9n;<\/li>\n<li>La <a href=\"https:\/\/www.famivita.com.br\/conteudo\/es\/categoria\/lactancia-materna\/\">lactancia materna<\/a> es otro proceso que desgasta mucho a la mujer, sobre todo por tener que despertarse durante la noche para alimentar al beb\u00e9. <strong>Prueba amamantar tumbada<\/strong> de lado, as\u00ed podr\u00e1s descansar y relajarte mientras das el pecho;<\/li>\n<li>Adem\u00e1s del sue\u00f1o al d\u00eda, la alimentaci\u00f3n es fundamental para recuperar las energ\u00edas. <strong>Bebe mucha agua<\/strong>, come alimentos saludables y haz las comidas en los horarios adecuados para tener mayor disposici\u00f3n;<\/li>\n<li><strong>Pide ayuda a amigos y familiares<\/strong>, especialmente a quienes se ofrecen para visitarte y sabes que est\u00e1n dispuestos a ayudar. Ayudar en las tareas como cocinar, cuidar a los dem\u00e1s hijos si los tienes o incluso quedarse con el beb\u00e9 mientras descansas un rato ser\u00e1 una gran ayuda.<\/li>\n<\/ul>\n<p class=\"align-justify\">Otro aspecto que pesa mucho en la vida de las mujeres y trae un gran desgaste despu\u00e9s del parto son las tareas dom\u00e9sticas. Rel\u00e1jate un poco con la obsesi\u00f3n por la casa, \u00a1o acabar\u00e1s volvi\u00e9ndote loca! Haz lo b\u00e1sico para mantenerla sin exigirte, y si puedes, contrata a alguien que te apoye al menos en los primeros meses de vida de tu beb\u00e9.<\/p>\n<p class=\"align-justify\">Foto: 789083<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1El gran d\u00eda ha llegado! Por fin conociste a ese peque\u00f1o ser que cambi\u00f3 tu vida, le dio m\u00e1s color a tu historia y trajo m\u00e1s expectativas a tu vida. Cuando llegas a casa, cada rinc\u00f3n y sus detalles, cuidados minuciosamente, empiezan a cobrar vida, pero junto con todo ese encanto, tambi\u00e9n llega el desgaste [&hellip;]<\/p>\n","protected":false},"author":471399,"featured_media":23111,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1021,1026,1022],"tags":[29,180,763,127],"class_list":["post-23110","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bebe-recien-nacido","category-madre-postparto","category-salud-bebe-recien-nacido","tag-parto","tag-posparto","tag-salud","tag-ser-madre"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Desgaste de la Mujer Despu\u00e9s del Parto | Famivita<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/desgaste-mujer-despues-parto\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Desgaste de la Mujer Despu\u00e9s del Parto | Famivita\" \/>\n<meta property=\"og:description\" content=\"\u00a1El gran d\u00eda ha llegado! Por fin conociste a ese peque\u00f1o ser que cambi\u00f3 tu vida, le dio m\u00e1s color a tu historia y trajo m\u00e1s expectativas a tu vida. Cuando llegas a casa, cada rinc\u00f3n y sus detalles, cuidados minuciosamente, empiezan a cobrar vida, pero junto con todo ese encanto, tambi\u00e9n llega el desgaste [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/desgaste-mujer-despues-parto\/\" \/>\n<meta property=\"og:site_name\" content=\"Famivita\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-15T11:28:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-16T10:52:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/wp-content\/uploads\/mulher-cansada-pos-parto.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"970\" \/>\n\t<meta property=\"og:image:height\" content=\"647\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dra. Mayara Belli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/desgaste-mujer-despues-parto\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/desgaste-mujer-despues-parto\/\"},\"author\":{\"name\":\"Dra. Mayara Belli\",\"@id\":\"https:\/\/www.famivita.com.br\/conteudo\/es\/#\/schema\/person\/1936f7c86b772cc44c19b926eee9cd53\"},\"headline\":\"Desgaste de la Mujer Despu\u00e9s del Parto\",\"datePublished\":\"2025-05-15T11:28:24+00:00\",\"dateModified\":\"2025-07-16T10:52:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/desgaste-mujer-despues-parto\/\"},\"wordCount\":829,\"commentCount\":1,\"image\":{\"@id\":\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/desgaste-mujer-despues-parto\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-content\/uploads\/mulher-cansada-pos-parto.jpg\",\"keywords\":[\"parto\",\"posparto\",\"salud\",\"ser madre\"],\"articleSection\":[\"Beb\u00e9 y Reci\u00e9n Nacido\",\"Madre Postparto\",\"Salud del Beb\u00e9 y Reci\u00e9n Nacido\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/desgaste-mujer-despues-parto\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/desgaste-mujer-despues-parto\/\",\"url\":\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/desgaste-mujer-despues-parto\/\",\"name\":\"Desgaste de la Mujer Despu\u00e9s del Parto | Famivita\",\"isPartOf\":{\"@id\":\"https:\/\/www.famivita.com.br\/conteudo\/es\/#website\",\"sameAs\":[\"https:\/\/www.instagram.com\/famivita\/\",\"https:\/\/www.facebook.com\/famivita\/\",\"https:\/\/www.youtube.com\/user\/trocandofraldasyt\",\"https:\/\/api.whatsapp.com\/send\/?phone=5511917837433\"]},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/desgaste-mujer-despues-parto\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/desgaste-mujer-despues-parto\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-content\/uploads\/mulher-cansada-pos-parto.jpg\",\"datePublished\":\"2025-05-15T11:28:24+00:00\",\"dateModified\":\"2025-07-16T10:52:31+00:00\",\"author\":{\"@id\":\"https:\/\/www.famivita.com.br\/conteudo\/es\/#\/schema\/person\/1936f7c86b772cc44c19b926eee9cd53\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/desgaste-mujer-despues-parto\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/desgaste-mujer-despues-parto\/\"]}],\"about\":{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.famivita.com.br\/#organization\",\"name\":\"Famivita\",\"logo\":\"https:\/\/www.famivita.com.br\/wp-content\/themes\/storefront-child\/header_footer_html\/images\/logo_mobile2.svg\",\"url\":\"https:\/\/www.famivita.com.br\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Rua Benedito Fernandes, 545, Santo Amaro\",\"addressLocality\":\"S\u00e3o Paulo\",\"addressRegion\":\"S\u00e3o Paulo\",\"postalCode\":\"04746-110\",\"addressCountry\":{\"@type\":\"Country\",\"name\":\"BR\"}}}},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/desgaste-mujer-despues-parto\/#primaryimage\",\"url\":\"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-content\/uploads\/mulher-cansada-pos-parto.jpg\",\"contentUrl\":\"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-content\/uploads\/mulher-cansada-pos-parto.jpg\",\"width\":970,\"height\":647,\"caption\":\"mulher cansada pos-parto\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/desgaste-mujer-despues-parto\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.famivita.com.br\/conteudo\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Beb\u00e9 y Reci\u00e9n Nacido\",\"item\":\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/categoria\/bebe-recien-nacido\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Salud del Beb\u00e9 y Reci\u00e9n Nacido\",\"item\":\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/categoria\/salud-bebe-recien-nacido\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Madre Postparto\",\"item\":\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/categoria\/madre-postparto\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Desgaste de la Mujer Despu\u00e9s del Parto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.famivita.com.br\/conteudo\/es\/#website\",\"url\":\"https:\/\/www.famivita.com.br\/conteudo\/es\/\",\"name\":\"Famivita\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.famivita.com.br\/conteudo\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.famivita.com.br\/conteudo\/es\/#\/schema\/person\/1936f7c86b772cc44c19b926eee9cd53\",\"name\":\"Dra. Mayara Belli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/8ed5f690ca67f8fdcb41678043ebff57ec60fda2206c36ce32b5a125f0c6915f?s=96&d=mm&r=g\",\"url\":\"https:\/\/www.famivita.com.br\/conteudo\/wp-content\/uploads\/2022\/08\/mayara-belli-top.jpg\",\"contentUrl\":\"https:\/\/www.famivita.com.br\/conteudo\/wp-content\/uploads\/2022\/08\/mayara-belli-top.jpg\",\"caption\":\"Dra. Mayara Belli\"},\"description\":\"Graduada en Nutrici\u00f3n por la Universidad Anhembi Morumbi. Tiene un posgrado en Nutrici\u00f3n Materno-Infantil y formaci\u00f3n en Nutrici\u00f3n y Fertilidad. Adem\u00e1s, est\u00e1 formada como Natural Chef (gastronom\u00eda funcional) y actualmente trabaja en el \u00e1rea cl\u00ednica atendiendo nutricionalmente a mujeres que desean quedar embarazadas, parejas, gestantes, lactantes, ni\u00f1os y salud de la mujer.\",\"sameAs\":[\"https:\/\/www.instagram.com\/nutri.futuramamae\/\"],\"url\":\"https:\/\/www.famivita.com.br\/conteudo\/es\/author\/dra-mayara-belli\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Desgaste de la Mujer Despu\u00e9s del Parto | Famivita","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/desgaste-mujer-despues-parto\/","og_locale":"es_ES","og_type":"article","og_title":"Desgaste de la Mujer Despu\u00e9s del Parto | Famivita","og_description":"\u00a1El gran d\u00eda ha llegado! Por fin conociste a ese peque\u00f1o ser que cambi\u00f3 tu vida, le dio m\u00e1s color a tu historia y trajo m\u00e1s expectativas a tu vida. Cuando llegas a casa, cada rinc\u00f3n y sus detalles, cuidados minuciosamente, empiezan a cobrar vida, pero junto con todo ese encanto, tambi\u00e9n llega el desgaste [&hellip;]","og_url":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/desgaste-mujer-despues-parto\/","og_site_name":"Famivita","article_published_time":"2025-05-15T11:28:24+00:00","article_modified_time":"2025-07-16T10:52:31+00:00","og_image":[{"width":970,"height":647,"url":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/wp-content\/uploads\/mulher-cansada-pos-parto.jpg","type":"image\/jpeg"}],"author":"Dra. Mayara Belli","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/desgaste-mujer-despues-parto\/#article","isPartOf":{"@id":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/desgaste-mujer-despues-parto\/"},"author":{"name":"Dra. Mayara Belli","@id":"https:\/\/www.famivita.com.br\/conteudo\/es\/#\/schema\/person\/1936f7c86b772cc44c19b926eee9cd53"},"headline":"Desgaste de la Mujer Despu\u00e9s del Parto","datePublished":"2025-05-15T11:28:24+00:00","dateModified":"2025-07-16T10:52:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/desgaste-mujer-despues-parto\/"},"wordCount":829,"commentCount":1,"image":{"@id":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/desgaste-mujer-despues-parto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-content\/uploads\/mulher-cansada-pos-parto.jpg","keywords":["parto","posparto","salud","ser madre"],"articleSection":["Beb\u00e9 y Reci\u00e9n Nacido","Madre Postparto","Salud del Beb\u00e9 y Reci\u00e9n Nacido"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.famivita.com.br\/conteudo\/es-dev\/desgaste-mujer-despues-parto\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/desgaste-mujer-despues-parto\/","url":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/desgaste-mujer-despues-parto\/","name":"Desgaste de la Mujer Despu\u00e9s del Parto | Famivita","isPartOf":{"@id":"https:\/\/www.famivita.com.br\/conteudo\/es\/#website","sameAs":["https:\/\/www.instagram.com\/famivita\/","https:\/\/www.facebook.com\/famivita\/","https:\/\/www.youtube.com\/user\/trocandofraldasyt","https:\/\/api.whatsapp.com\/send\/?phone=5511917837433"]},"primaryImageOfPage":{"@id":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/desgaste-mujer-despues-parto\/#primaryimage"},"image":{"@id":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/desgaste-mujer-despues-parto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-content\/uploads\/mulher-cansada-pos-parto.jpg","datePublished":"2025-05-15T11:28:24+00:00","dateModified":"2025-07-16T10:52:31+00:00","author":{"@id":"https:\/\/www.famivita.com.br\/conteudo\/es\/#\/schema\/person\/1936f7c86b772cc44c19b926eee9cd53"},"breadcrumb":{"@id":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/desgaste-mujer-despues-parto\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.famivita.com.br\/conteudo\/es-dev\/desgaste-mujer-despues-parto\/"]}],"about":{"@type":"Organization","@id":"https:\/\/www.famivita.com.br\/#organization","name":"Famivita","logo":"https:\/\/www.famivita.com.br\/wp-content\/themes\/storefront-child\/header_footer_html\/images\/logo_mobile2.svg","url":"https:\/\/www.famivita.com.br\/","address":{"@type":"PostalAddress","streetAddress":"Rua Benedito Fernandes, 545, Santo Amaro","addressLocality":"S\u00e3o Paulo","addressRegion":"S\u00e3o Paulo","postalCode":"04746-110","addressCountry":{"@type":"Country","name":"BR"}}}},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/desgaste-mujer-despues-parto\/#primaryimage","url":"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-content\/uploads\/mulher-cansada-pos-parto.jpg","contentUrl":"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-content\/uploads\/mulher-cansada-pos-parto.jpg","width":970,"height":647,"caption":"mulher cansada pos-parto"},{"@type":"BreadcrumbList","@id":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/desgaste-mujer-despues-parto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.famivita.com.br\/conteudo\/es\/"},{"@type":"ListItem","position":2,"name":"Beb\u00e9 y Reci\u00e9n Nacido","item":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/categoria\/bebe-recien-nacido\/"},{"@type":"ListItem","position":3,"name":"Salud del Beb\u00e9 y Reci\u00e9n Nacido","item":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/categoria\/salud-bebe-recien-nacido\/"},{"@type":"ListItem","position":4,"name":"Madre Postparto","item":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/categoria\/madre-postparto\/"},{"@type":"ListItem","position":5,"name":"Desgaste de la Mujer Despu\u00e9s del Parto"}]},{"@type":"WebSite","@id":"https:\/\/www.famivita.com.br\/conteudo\/es\/#website","url":"https:\/\/www.famivita.com.br\/conteudo\/es\/","name":"Famivita","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.famivita.com.br\/conteudo\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.famivita.com.br\/conteudo\/es\/#\/schema\/person\/1936f7c86b772cc44c19b926eee9cd53","name":"Dra. Mayara Belli","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8ed5f690ca67f8fdcb41678043ebff57ec60fda2206c36ce32b5a125f0c6915f?s=96&d=mm&r=g","url":"https:\/\/www.famivita.com.br\/conteudo\/wp-content\/uploads\/2022\/08\/mayara-belli-top.jpg","contentUrl":"https:\/\/www.famivita.com.br\/conteudo\/wp-content\/uploads\/2022\/08\/mayara-belli-top.jpg","caption":"Dra. Mayara Belli"},"description":"Graduada en Nutrici\u00f3n por la Universidad Anhembi Morumbi. Tiene un posgrado en Nutrici\u00f3n Materno-Infantil y formaci\u00f3n en Nutrici\u00f3n y Fertilidad. Adem\u00e1s, est\u00e1 formada como Natural Chef (gastronom\u00eda funcional) y actualmente trabaja en el \u00e1rea cl\u00ednica atendiendo nutricionalmente a mujeres que desean quedar embarazadas, parejas, gestantes, lactantes, ni\u00f1os y salud de la mujer.","sameAs":["https:\/\/www.instagram.com\/nutri.futuramamae\/"],"url":"https:\/\/www.famivita.com.br\/conteudo\/es\/author\/dra-mayara-belli\/"}]}},"_links":{"self":[{"href":"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-json\/wp\/v2\/posts\/23110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-json\/wp\/v2\/users\/471399"}],"replies":[{"embeddable":true,"href":"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-json\/wp\/v2\/comments?post=23110"}],"version-history":[{"count":3,"href":"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-json\/wp\/v2\/posts\/23110\/revisions"}],"predecessor-version":[{"id":161165,"href":"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-json\/wp\/v2\/posts\/23110\/revisions\/161165"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-json\/wp\/v2\/media\/23111"}],"wp:attachment":[{"href":"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-json\/wp\/v2\/media?parent=23110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-json\/wp\/v2\/categories?post=23110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-json\/wp\/v2\/tags?post=23110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}