{"id":42752,"date":"2025-05-15T08:32:39","date_gmt":"2025-05-15T11:32:39","guid":{"rendered":"https:\/\/www.famivita.com.br\/conteudo\/es\/?p=42752"},"modified":"2025-07-16T07:49:31","modified_gmt":"2025-07-16T10:49:31","slug":"diversidad-escuelas-lidiar-diferencias","status":"publish","type":"post","link":"https:\/\/www.famivita.com.br\/conteudo\/es\/diversidad-escuelas-lidiar-diferencias\/","title":{"rendered":"Diversidad en las Escuelas &#8211; \u00bfC\u00f3mo Lidiar con las Diferencias?"},"content":{"rendered":"<p>Cuando un ni\u00f1o va a la escuela, empieza a aprender no solo el contenido que se le ense\u00f1a en clase, sino tambi\u00e9n a convivir con otras personas. Este segundo punto es, sobre todo, un indicativo de por qu\u00e9 es saludable que los ni\u00f1os vayan a la escuela y no estudien solos en casa, por ejemplo.  <\/p>\n<p>La escuela es un entorno de interacci\u00f3n, de aprendizaje y de <strong>desarrollo social<\/strong>. Es donde se aprende que no todas las personas son iguales, que existen opiniones diferentes, formas distintas de ver la vida y muchas otras culturas.<br \/>\nLa diversidad en las escuelas es fundamental para que un <strong>ni\u00f1o crezca sin prejuicios<\/strong>, con la mente abierta y, como consecuencia, con una convivencia social m\u00e1s saludable. <\/p>\n<p>Muchos pueden pensar que temas como el prejuicio y el racismo no afectan a los ni\u00f1os y que deber\u00edan mantenerse al margen, pero la verdad es que todo tipo de pensamiento discriminatorio se forma en gran parte durante la infancia y la influencia de la escuela para que este pensamiento no se convierta en algo peor en el futuro es enorme. <\/p>\n<p>Por esta raz\u00f3n vamos a abordar hoy el tema de la diversidad en las escuelas, su importancia y c\u00f3mo afecta a los ni\u00f1os en la actualidad.<\/p>\n<h3>Hay que Valorar la Diversidad <\/h3>\n<p>Cuanto antes aprenda un ni\u00f1o que personas diferentes habitan los mismos lugares todos los d\u00edas, m\u00e1s saludable ser\u00e1 para \u00e9l. Cuando un ni\u00f1o es privado de este contacto con lo diferente, puede acabar extra\u00f1\u00e1ndolo en el futuro, lo que puede causarle problemas sociales.  <\/p>\n<p>Dentro de las aulas y desde muy peque\u00f1os, los ni\u00f1os deben <strong>aprender a lidiar con esas diferencias<\/strong>, tanto en lo que se les ense\u00f1a como en la pr\u00e1ctica, realizando trabajos con ni\u00f1os distintos, jugando en el recreo con peque\u00f1os de otras clases, etc.  <\/p>\n<h3>Racismo y Prejuicio <\/h3>\n<p>El racismo es una realidad que existe en nuestro pa\u00eds, lamentablemente. Pero para que esto cambie, nuestra postura frente a ese problema tambi\u00e9n debe cambiar. Esto no significa que debas intentar forzar la amistad de tus hijos con ni\u00f1os de otro color o algo por el estilo, simplemente que tu hijo debe crecer con <strong>la idea de que el color de piel no influye<\/strong> en ning\u00fan otro aspecto de la vida de una persona. <\/p>\n<h3>\u00bfC\u00f3mo Lidiar con la Diversidad en las Escuelas? <\/h3>\n<p>Cuando hablamos de diversidad en la escuela, hablamos tambi\u00e9n de estimular la integraci\u00f3n de alumnos de todos los colores, religiones y clases sociales presentes. <strong>En Brasil, esto puede variar mucho<\/strong> dependiendo de la escuela donde estudie el ni\u00f1o o inclusive de la regi\u00f3n del pa\u00eds. Sin embargo, la idea que debemos sembrar en todos sigue siendo la misma.  <\/p>\n<p>En la escuela los ni\u00f1os tambi\u00e9n deben aprender que la discriminaci\u00f3n es algo negativo. Una de las mejores formas de hacerlo es evitar que las \u00abpandillas\u00bb escolares, tan comunes, intenten <strong>menospreciar a otros alumnos<\/strong> por cualquier motivo.  <\/p>\n<p>Puede parecer algo trivial, pero es esencial tanto para el ni\u00f1o que agrede como para el que es agredido, que este tipo de comportamiento se detenga cuanto antes. Como ya dijimos, cuanto antes aprenda el ni\u00f1o a lidiar con las diferencias, m\u00e1s saludable ser\u00e1 para \u00e9l. <\/p>\n<p>Todos estos puntos forman parte del <strong>papel de una educadora<\/strong> y de un educador. Ya sea una maestra de educaci\u00f3n b\u00e1sica o una profesora de alguna materia espec\u00edfica de primaria.  <\/p>\n<p>Es sumamente importante que todos los profesionales implicados en la educaci\u00f3n de los ni\u00f1os est\u00e9n atentos a la forma en la que ellos manejan la diversidad en la escuela. Es deber de todos estos profesionales corregir los errores que son comunes en la infancia, pero que no deben llevarse a la vida adulta. <\/p>\n<p><a href=\"https:\/\/www.famivita.com.br\/conteudo\/wp-content\/uploads\/2018\/08\/two-caucasian-and-two-african-american-children-playing-together-725x483.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.famivita.com.br\/conteudo\/wp-content\/uploads\/2018\/08\/two-caucasian-and-two-african-american-children-playing-together-725x483-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" class=\"aligncenter size-medium wp-image-42753\" srcset=\"https:\/\/www.famivita.com.br\/conteudo\/wp-content\/uploads\/2018\/08\/two-caucasian-and-two-african-american-children-playing-together-725x483-300x200.jpg 300w, https:\/\/www.famivita.com.br\/conteudo\/wp-content\/uploads\/2018\/08\/two-caucasian-and-two-african-american-children-playing-together-725x483-500x333.jpg 500w, https:\/\/www.famivita.com.br\/conteudo\/wp-content\/uploads\/2018\/08\/two-caucasian-and-two-african-american-children-playing-together-725x483.jpg 725w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<h3>El Acompa\u00f1amiento de los Padres es Esencial <\/h3>\n<p>La figura de los padres marcar\u00e1 toda la diferencia y es fundamental para la formaci\u00f3n social del ni\u00f1o. Sabiendo esto, acompa\u00f1ar al ni\u00f1o y saber c\u00f3mo enfrenta la diversidad en la escuela es una obligaci\u00f3n que se debe cumplir.  <\/p>\n<p>Recuerda que los ni\u00f1os aprenden mucho m\u00e1s del ejemplo que dan los padres y no de lo que dicen, en otras palabras, demostrar actos de buena convivencia con las diferencias es una actitud importante para que puedan reproducir este comportamiento en la escuela.  <\/p>\n<p>Lo contrario tambi\u00e9n es cierto: cuando los padres muestran actitudes racistas o discriminatorias delante de sus hijos, aunque sea sin intenci\u00f3n, acaban haciendo que el ni\u00f1o asuma eso como algo normal o correcto, lo cual puede perjudicar su entendimiento sobre la diversidad.  <\/p>\n<p>Est\u00e1 claro que existe un <strong>choque generacional<\/strong> entre lo que muchos padres aprendieron en la infancia y lo que se transmite hoy en d\u00eda, pero es necesario entender que la diversidad es un tema importante y que ciertas actitudes que antes eran socialmente aceptadas ahora ya no son bien vistas. <\/p>\n<p>Desafortunadamente vivimos en una sociedad donde el racismo, los prejuicios y la discriminaci\u00f3n son cosas reales y que no afectan solo a los adultos. Y el mayor problema no es que estas actitudes simplemente lleguen a los ni\u00f1os, sino que pueden terminar siendo afectados y transmitir actitudes similares a ra\u00edz de su crianza.<\/p>\n<p>Por eso, lidiar con la <strong>diversidad en las escuelas es una de las armas m\u00e1s poderosas<\/strong> para que este tipo de problema no persista en el futuro. Por supuesto que no es un trabajo cuyos resultados se ven de la noche a la ma\u00f1ana y ninguna escuela puede transformar el mundo por s\u00ed sola. Pero cada peque\u00f1o gesto que hacemos es un paso m\u00e1s que damos hacia un mundo mejor para que los ni\u00f1os vivan.<\/p>\n<p>Mira tambi\u00e9n: <a href=\"https:\/\/www.famivita.com.br\/conteudo\/es\/\">Tema pol\u00e9mico: Hijos de Padres Gays <\/a><br \/>\nFoto: Cade Martin, Dawn Arlotta<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuando un ni\u00f1o va a la escuela, empieza a aprender no solo el contenido que se le ense\u00f1a en clase, sino tambi\u00e9n a convivir con otras personas. Este segundo punto es, sobre todo, un indicativo de por qu\u00e9 es saludable que los ni\u00f1os vayan a la escuela y no estudien solos en casa, por ejemplo. [&hellip;]<\/p>\n","protected":false},"author":471399,"featured_media":42753,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1032],"tags":[162,961,34],"class_list":["post-42752","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion-infantil","tag-educacion","tag-escuela","tag-ninos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Diversidad en las Escuelas - \u00bfC\u00f3mo Lidiar con las Diferencias? | Famivita<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/diversidad-escuelas-lidiar-diferencias\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Diversidad en las Escuelas - \u00bfC\u00f3mo Lidiar con las Diferencias? | Famivita\" \/>\n<meta property=\"og:description\" content=\"Cuando un ni\u00f1o va a la escuela, empieza a aprender no solo el contenido que se le ense\u00f1a en clase, sino tambi\u00e9n a convivir con otras personas. Este segundo punto es, sobre todo, un indicativo de por qu\u00e9 es saludable que los ni\u00f1os vayan a la escuela y no estudien solos en casa, por ejemplo. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/diversidad-escuelas-lidiar-diferencias\/\" \/>\n<meta property=\"og:site_name\" content=\"Famivita\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-15T11:32:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-16T10:49:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/wp-content\/uploads\/2018\/08\/two-caucasian-and-two-african-american-children-playing-together-725x483.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"725\" \/>\n\t<meta property=\"og:image:height\" content=\"483\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dra. Mayara Belli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/diversidad-escuelas-lidiar-diferencias\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/diversidad-escuelas-lidiar-diferencias\/\"},\"author\":{\"name\":\"Dra. Mayara Belli\",\"@id\":\"https:\/\/www.famivita.com.br\/conteudo\/es\/#\/schema\/person\/1936f7c86b772cc44c19b926eee9cd53\"},\"headline\":\"Diversidad en las Escuelas &#8211; \u00bfC\u00f3mo Lidiar con las Diferencias?\",\"datePublished\":\"2025-05-15T11:32:39+00:00\",\"dateModified\":\"2025-07-16T10:49:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/diversidad-escuelas-lidiar-diferencias\/\"},\"wordCount\":1008,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/diversidad-escuelas-lidiar-diferencias\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-content\/uploads\/2018\/08\/two-caucasian-and-two-african-american-children-playing-together-725x483.jpg\",\"keywords\":[\"educaci\u00f3n\",\"escuela\",\"ni\u00f1os\"],\"articleSection\":[\"Educaci\u00f3n Infantil\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/diversidad-escuelas-lidiar-diferencias\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/diversidad-escuelas-lidiar-diferencias\/\",\"url\":\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/diversidad-escuelas-lidiar-diferencias\/\",\"name\":\"Diversidad en las Escuelas - \u00bfC\u00f3mo Lidiar con las Diferencias? | Famivita\",\"isPartOf\":{\"@id\":\"https:\/\/www.famivita.com.br\/conteudo\/es\/#website\",\"sameAs\":[\"https:\/\/www.instagram.com\/famivita\/\",\"https:\/\/www.facebook.com\/famivita\/\",\"https:\/\/www.youtube.com\/user\/trocandofraldasyt\",\"https:\/\/api.whatsapp.com\/send\/?phone=5511917837433\"]},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/diversidad-escuelas-lidiar-diferencias\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/diversidad-escuelas-lidiar-diferencias\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-content\/uploads\/2018\/08\/two-caucasian-and-two-african-american-children-playing-together-725x483.jpg\",\"datePublished\":\"2025-05-15T11:32:39+00:00\",\"dateModified\":\"2025-07-16T10:49:31+00:00\",\"author\":{\"@id\":\"https:\/\/www.famivita.com.br\/conteudo\/es\/#\/schema\/person\/1936f7c86b772cc44c19b926eee9cd53\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/diversidad-escuelas-lidiar-diferencias\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/diversidad-escuelas-lidiar-diferencias\/\"]}],\"about\":{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.famivita.com.br\/#organization\",\"name\":\"Famivita\",\"logo\":\"https:\/\/www.famivita.com.br\/wp-content\/themes\/storefront-child\/header_footer_html\/images\/logo_mobile2.svg\",\"url\":\"https:\/\/www.famivita.com.br\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Rua Benedito Fernandes, 545, Santo Amaro\",\"addressLocality\":\"S\u00e3o Paulo\",\"addressRegion\":\"S\u00e3o Paulo\",\"postalCode\":\"04746-110\",\"addressCountry\":{\"@type\":\"Country\",\"name\":\"BR\"}}}},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/diversidad-escuelas-lidiar-diferencias\/#primaryimage\",\"url\":\"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-content\/uploads\/2018\/08\/two-caucasian-and-two-african-american-children-playing-together-725x483.jpg\",\"contentUrl\":\"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-content\/uploads\/2018\/08\/two-caucasian-and-two-african-american-children-playing-together-725x483.jpg\",\"width\":725,\"height\":483,\"caption\":\"criancas brincando\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/diversidad-escuelas-lidiar-diferencias\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.famivita.com.br\/conteudo\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ni\u00f1os\",\"item\":\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/categoria\/ninos\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Educaci\u00f3n Infantil\",\"item\":\"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/categoria\/educacion-infantil\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Diversidad en las Escuelas &#8211; \u00bfC\u00f3mo Lidiar con las Diferencias?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.famivita.com.br\/conteudo\/es\/#website\",\"url\":\"https:\/\/www.famivita.com.br\/conteudo\/es\/\",\"name\":\"Famivita\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.famivita.com.br\/conteudo\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.famivita.com.br\/conteudo\/es\/#\/schema\/person\/1936f7c86b772cc44c19b926eee9cd53\",\"name\":\"Dra. Mayara Belli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/8ed5f690ca67f8fdcb41678043ebff57ec60fda2206c36ce32b5a125f0c6915f?s=96&d=mm&r=g\",\"url\":\"https:\/\/www.famivita.com.br\/conteudo\/wp-content\/uploads\/2022\/08\/mayara-belli-top.jpg\",\"contentUrl\":\"https:\/\/www.famivita.com.br\/conteudo\/wp-content\/uploads\/2022\/08\/mayara-belli-top.jpg\",\"caption\":\"Dra. Mayara Belli\"},\"description\":\"Graduada en Nutrici\u00f3n por la Universidad Anhembi Morumbi. Tiene un posgrado en Nutrici\u00f3n Materno-Infantil y formaci\u00f3n en Nutrici\u00f3n y Fertilidad. Adem\u00e1s, est\u00e1 formada como Natural Chef (gastronom\u00eda funcional) y actualmente trabaja en el \u00e1rea cl\u00ednica atendiendo nutricionalmente a mujeres que desean quedar embarazadas, parejas, gestantes, lactantes, ni\u00f1os y salud de la mujer.\",\"sameAs\":[\"https:\/\/www.instagram.com\/nutri.futuramamae\/\"],\"url\":\"https:\/\/www.famivita.com.br\/conteudo\/es\/author\/dra-mayara-belli\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Diversidad en las Escuelas - \u00bfC\u00f3mo Lidiar con las Diferencias? | Famivita","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/diversidad-escuelas-lidiar-diferencias\/","og_locale":"es_ES","og_type":"article","og_title":"Diversidad en las Escuelas - \u00bfC\u00f3mo Lidiar con las Diferencias? | Famivita","og_description":"Cuando un ni\u00f1o va a la escuela, empieza a aprender no solo el contenido que se le ense\u00f1a en clase, sino tambi\u00e9n a convivir con otras personas. Este segundo punto es, sobre todo, un indicativo de por qu\u00e9 es saludable que los ni\u00f1os vayan a la escuela y no estudien solos en casa, por ejemplo. [&hellip;]","og_url":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/diversidad-escuelas-lidiar-diferencias\/","og_site_name":"Famivita","article_published_time":"2025-05-15T11:32:39+00:00","article_modified_time":"2025-07-16T10:49:31+00:00","og_image":[{"width":725,"height":483,"url":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/wp-content\/uploads\/2018\/08\/two-caucasian-and-two-african-american-children-playing-together-725x483.jpg","type":"image\/jpeg"}],"author":"Dra. Mayara Belli","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/diversidad-escuelas-lidiar-diferencias\/#article","isPartOf":{"@id":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/diversidad-escuelas-lidiar-diferencias\/"},"author":{"name":"Dra. Mayara Belli","@id":"https:\/\/www.famivita.com.br\/conteudo\/es\/#\/schema\/person\/1936f7c86b772cc44c19b926eee9cd53"},"headline":"Diversidad en las Escuelas &#8211; \u00bfC\u00f3mo Lidiar con las Diferencias?","datePublished":"2025-05-15T11:32:39+00:00","dateModified":"2025-07-16T10:49:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/diversidad-escuelas-lidiar-diferencias\/"},"wordCount":1008,"commentCount":0,"image":{"@id":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/diversidad-escuelas-lidiar-diferencias\/#primaryimage"},"thumbnailUrl":"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-content\/uploads\/2018\/08\/two-caucasian-and-two-african-american-children-playing-together-725x483.jpg","keywords":["educaci\u00f3n","escuela","ni\u00f1os"],"articleSection":["Educaci\u00f3n Infantil"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.famivita.com.br\/conteudo\/es-dev\/diversidad-escuelas-lidiar-diferencias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/diversidad-escuelas-lidiar-diferencias\/","url":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/diversidad-escuelas-lidiar-diferencias\/","name":"Diversidad en las Escuelas - \u00bfC\u00f3mo Lidiar con las Diferencias? | Famivita","isPartOf":{"@id":"https:\/\/www.famivita.com.br\/conteudo\/es\/#website","sameAs":["https:\/\/www.instagram.com\/famivita\/","https:\/\/www.facebook.com\/famivita\/","https:\/\/www.youtube.com\/user\/trocandofraldasyt","https:\/\/api.whatsapp.com\/send\/?phone=5511917837433"]},"primaryImageOfPage":{"@id":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/diversidad-escuelas-lidiar-diferencias\/#primaryimage"},"image":{"@id":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/diversidad-escuelas-lidiar-diferencias\/#primaryimage"},"thumbnailUrl":"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-content\/uploads\/2018\/08\/two-caucasian-and-two-african-american-children-playing-together-725x483.jpg","datePublished":"2025-05-15T11:32:39+00:00","dateModified":"2025-07-16T10:49:31+00:00","author":{"@id":"https:\/\/www.famivita.com.br\/conteudo\/es\/#\/schema\/person\/1936f7c86b772cc44c19b926eee9cd53"},"breadcrumb":{"@id":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/diversidad-escuelas-lidiar-diferencias\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.famivita.com.br\/conteudo\/es-dev\/diversidad-escuelas-lidiar-diferencias\/"]}],"about":{"@type":"Organization","@id":"https:\/\/www.famivita.com.br\/#organization","name":"Famivita","logo":"https:\/\/www.famivita.com.br\/wp-content\/themes\/storefront-child\/header_footer_html\/images\/logo_mobile2.svg","url":"https:\/\/www.famivita.com.br\/","address":{"@type":"PostalAddress","streetAddress":"Rua Benedito Fernandes, 545, Santo Amaro","addressLocality":"S\u00e3o Paulo","addressRegion":"S\u00e3o Paulo","postalCode":"04746-110","addressCountry":{"@type":"Country","name":"BR"}}}},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/diversidad-escuelas-lidiar-diferencias\/#primaryimage","url":"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-content\/uploads\/2018\/08\/two-caucasian-and-two-african-american-children-playing-together-725x483.jpg","contentUrl":"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-content\/uploads\/2018\/08\/two-caucasian-and-two-african-american-children-playing-together-725x483.jpg","width":725,"height":483,"caption":"criancas brincando"},{"@type":"BreadcrumbList","@id":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/diversidad-escuelas-lidiar-diferencias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.famivita.com.br\/conteudo\/es\/"},{"@type":"ListItem","position":2,"name":"Ni\u00f1os","item":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/categoria\/ninos\/"},{"@type":"ListItem","position":3,"name":"Educaci\u00f3n Infantil","item":"https:\/\/www.famivita.com.br\/conteudo\/es-dev\/categoria\/educacion-infantil\/"},{"@type":"ListItem","position":4,"name":"Diversidad en las Escuelas &#8211; \u00bfC\u00f3mo Lidiar con las Diferencias?"}]},{"@type":"WebSite","@id":"https:\/\/www.famivita.com.br\/conteudo\/es\/#website","url":"https:\/\/www.famivita.com.br\/conteudo\/es\/","name":"Famivita","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.famivita.com.br\/conteudo\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.famivita.com.br\/conteudo\/es\/#\/schema\/person\/1936f7c86b772cc44c19b926eee9cd53","name":"Dra. Mayara Belli","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8ed5f690ca67f8fdcb41678043ebff57ec60fda2206c36ce32b5a125f0c6915f?s=96&d=mm&r=g","url":"https:\/\/www.famivita.com.br\/conteudo\/wp-content\/uploads\/2022\/08\/mayara-belli-top.jpg","contentUrl":"https:\/\/www.famivita.com.br\/conteudo\/wp-content\/uploads\/2022\/08\/mayara-belli-top.jpg","caption":"Dra. Mayara Belli"},"description":"Graduada en Nutrici\u00f3n por la Universidad Anhembi Morumbi. Tiene un posgrado en Nutrici\u00f3n Materno-Infantil y formaci\u00f3n en Nutrici\u00f3n y Fertilidad. Adem\u00e1s, est\u00e1 formada como Natural Chef (gastronom\u00eda funcional) y actualmente trabaja en el \u00e1rea cl\u00ednica atendiendo nutricionalmente a mujeres que desean quedar embarazadas, parejas, gestantes, lactantes, ni\u00f1os y salud de la mujer.","sameAs":["https:\/\/www.instagram.com\/nutri.futuramamae\/"],"url":"https:\/\/www.famivita.com.br\/conteudo\/es\/author\/dra-mayara-belli\/"}]}},"_links":{"self":[{"href":"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-json\/wp\/v2\/posts\/42752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-json\/wp\/v2\/users\/471399"}],"replies":[{"embeddable":true,"href":"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-json\/wp\/v2\/comments?post=42752"}],"version-history":[{"count":2,"href":"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-json\/wp\/v2\/posts\/42752\/revisions"}],"predecessor-version":[{"id":160738,"href":"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-json\/wp\/v2\/posts\/42752\/revisions\/160738"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-json\/wp\/v2\/media\/42753"}],"wp:attachment":[{"href":"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-json\/wp\/v2\/media?parent=42752"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-json\/wp\/v2\/categories?post=42752"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.famivita.com.br\/conteudo\/es\/wp-json\/wp\/v2\/tags?post=42752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}